{"id":426,"date":"2023-02-28T17:14:49","date_gmt":"2023-02-28T10:14:49","guid":{"rendered":"https:\/\/www.qdlashfine.com\/?post_type=product&#038;p=426"},"modified":"2023-12-20T14:16:00","modified_gmt":"2023-12-20T06:16:00","slug":"klassieke-wimpers-gemengd-blad","status":"publish","type":"product","link":"https:\/\/qdlashfine.com\/nl\/product\/klassieke-wimpers-gemengd-blad\/","title":{"rendered":"klassieke wimpers gemengd blad (0,03 mm)"},"content":{"rendered":"<p>Introductie van Lashfine klassieke wimpers - De beste kwaliteit wimperfabriek die je kunt vinden in China<\/p>\n<p>Onze klassieke wimpers zijn gemaakt van de beste Koreaanse PBT-vezels, zorgvuldig geselecteerd om de zachte, fladderige textuur van natuurlijke wimpers na te bootsen. Ze zijn licht van gewicht, comfortabel en gemakkelijk aan te brengen. Het is het streven van elke wimpertransplantatietechnicus.<\/p>\n<p>Met onze klassieke wimpers kun je verschillende stijlen cre\u00ebren voor je klanten, van een subtiele, alledaagse look tot een meer dramatische, avondlook. Onze wimpers zijn verkrijgbaar in verschillende lengtes en diktes.<\/p>\n<p>Onze wimpers zijn zorgvuldig ontworpen om langhoudend en duurzaam te zijn, zodat je wekenlang kunt genieten van prachtige, weelderige wimpers. Ze zijn ook gemakkelijk te verzorgen en te onderhouden, met eenvoudige instructies om ervoor te zorgen dat je wimpers in perfecte conditie blijven.<\/p>\n<p>Dus waarom wachten? Neem nu contact met ons op om de laatste offerte voor onze producten te krijgen, we kunnen gratis monsters leveren om te testen!<\/p>\n<p>We kunnen niet wachten om je de beste producten en diensten te leveren!<\/p>","protected":false},"excerpt":{"rendered":"<p>Naam van het item: klassieke wimper extensies<\/p>\n<p>Dikte: 0,03 mm<\/p>\n<p>Kenmerken\uff1a<\/p>\n<p>Natuurlijke kleur: Lashfine zwarte klassieke wimpers geven je een uniek en charmant natuurlijk effect.<\/p>\n<p>Grote krul: Speciale krommingstechnologie zorgt ervoor dat de krullen lang blijven zitten, waardoor je een natuurlijke en charmante uitstraling of display krijgt.<\/p>\n<p>Hoogwaardige materialen: De wimpers zijn gemaakt van hoogwaardig PBT-materiaal en zijn 100% handgemaakt, zacht en natuurlijk, waardoor ze de beste keuze zijn voor professionele salons.<\/p>","protected":false},"featured_media":428,"template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[26],"product_tag":[],"class_list":["post-426","product","type-product","status-publish","has-post-thumbnail","product_cat-classic-lashes","desktop-align-left","tablet-align-left","mobile-align-left","ast-product-gallery-layout-horizontal-slider","ast-product-tabs-layout-horizontal","first","instock","shipping-taxable","product-type-simple"],"spectra_custom_meta":{"_edit_last":["1"],"_edit_lock":["1703052820:1"],"_thumbnail_id":["428"],"total_sales":["0"],"_tax_status":["taxable"],"_tax_class":[""],"_manage_stock":["no"],"_backorders":["no"],"_sold_individually":["no"],"_virtual":["no"],"_downloadable":["no"],"_download_limit":["-1"],"_download_expiry":["-1"],"_stock":[null],"_stock_status":["instock"],"_wc_average_rating":["0"],"_wc_review_count":["0"],"_product_version":["8.3.0"],"_fl_builder_history_position":["0"],"_fl_builder_history_state_0":["a:4:{s:5:\"label\";s:13:\"draft_created\";s:11:\"module_type\";N;s:5:\"nodes\";a:0:{}s:8:\"settings\";a:2:{s:6:\"global\";O:8:\"stdClass\":118:{s:20:\"show_default_heading\";s:1:\"0\";s:24:\"default_heading_selector\";s:15:\".fl-post-header\";s:9:\"row_width\";i:1100;s:14:\"row_width_unit\";s:2:\"px\";s:17:\"row_width_default\";s:5:\"fixed\";s:25:\"row_content_width_default\";s:5:\"fixed\";s:18:\"responsive_enabled\";s:1:\"1\";s:12:\"auto_spacing\";s:1:\"1\";s:16:\"large_breakpoint\";i:1200;s:17:\"medium_breakpoint\";i:992;s:21:\"responsive_breakpoint\";i:768;s:18:\"responsive_preview\";s:1:\"0\";s:24:\"responsive_col_max_width\";s:1:\"1\";s:24:\"responsive_base_fontsize\";i:16;s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";s:10:\"shape_form\";a:1:{i:0;O:8:\"stdClass\":1:{s:1:\"0\";s:0:\"\";}}s:15:\"row_margins_top\";s:1:\"0\";s:16:\"row_margins_unit\";s:2:\"px\";s:21:\"row_margins_top_large\";s:0:\"\";s:22:\"row_margins_large_unit\";s:2:\"px\";s:22:\"row_margins_top_medium\";s:0:\"\";s:23:\"row_margins_medium_unit\";s:2:\"px\";s:26:\"row_margins_top_responsive\";s:0:\"\";s:27:\"row_margins_responsive_unit\";s:2:\"px\";s:17:\"row_margins_right\";s:1:\"0\";s:23:\"row_margins_right_large\";s:0:\"\";s:24:\"row_margins_right_medium\";s:0:\"\";s:28:\"row_margins_right_responsive\";s:0:\"\";s:18:\"row_margins_bottom\";s:1:\"0\";s:24:\"row_margins_bottom_large\";s:0:\"\";s:25:\"row_margins_bottom_medium\";s:0:\"\";s:29:\"row_margins_bottom_responsive\";s:0:\"\";s:16:\"row_margins_left\";s:1:\"0\";s:22:\"row_margins_left_large\";s:0:\"\";s:23:\"row_margins_left_medium\";s:0:\"\";s:27:\"row_margins_left_responsive\";s:0:\"\";s:15:\"row_padding_top\";s:2:\"20\";s:16:\"row_padding_unit\";s:2:\"px\";s:21:\"row_padding_top_large\";s:0:\"\";s:22:\"row_padding_large_unit\";s:2:\"px\";s:22:\"row_padding_top_medium\";s:0:\"\";s:23:\"row_padding_medium_unit\";s:2:\"px\";s:26:\"row_padding_top_responsive\";s:0:\"\";s:27:\"row_padding_responsive_unit\";s:2:\"px\";s:17:\"row_padding_right\";s:2:\"20\";s:23:\"row_padding_right_large\";s:0:\"\";s:24:\"row_padding_right_medium\";s:0:\"\";s:28:\"row_padding_right_responsive\";s:0:\"\";s:18:\"row_padding_bottom\";s:2:\"20\";s:24:\"row_padding_bottom_large\";s:0:\"\";s:25:\"row_padding_bottom_medium\";s:0:\"\";s:29:\"row_padding_bottom_responsive\";s:0:\"\";s:16:\"row_padding_left\";s:2:\"20\";s:22:\"row_padding_left_large\";s:0:\"\";s:23:\"row_padding_left_medium\";s:0:\"\";s:27:\"row_padding_left_responsive\";s:0:\"\";s:18:\"column_margins_top\";s:0:\"\";s:19:\"column_margins_unit\";s:2:\"px\";s:24:\"column_margins_top_large\";s:0:\"\";s:25:\"column_margins_large_unit\";s:2:\"px\";s:25:\"column_margins_top_medium\";s:0:\"\";s:26:\"column_margins_medium_unit\";s:2:\"px\";s:29:\"column_margins_top_responsive\";s:0:\"\";s:30:\"column_margins_responsive_unit\";s:2:\"px\";s:20:\"column_margins_right\";s:0:\"\";s:26:\"column_margins_right_large\";s:0:\"\";s:27:\"column_margins_right_medium\";s:0:\"\";s:31:\"column_margins_right_responsive\";s:0:\"\";s:21:\"column_margins_bottom\";s:0:\"\";s:27:\"column_margins_bottom_large\";s:0:\"\";s:28:\"column_margins_bottom_medium\";s:0:\"\";s:32:\"column_margins_bottom_responsive\";s:0:\"\";s:19:\"column_margins_left\";s:0:\"\";s:25:\"column_margins_left_large\";s:0:\"\";s:26:\"column_margins_left_medium\";s:0:\"\";s:30:\"column_margins_left_responsive\";s:0:\"\";s:18:\"column_padding_top\";s:0:\"\";s:19:\"column_padding_unit\";s:2:\"px\";s:24:\"column_padding_top_large\";s:0:\"\";s:25:\"column_padding_large_unit\";s:2:\"px\";s:25:\"column_padding_top_medium\";s:0:\"\";s:26:\"column_padding_medium_unit\";s:2:\"px\";s:29:\"column_padding_top_responsive\";s:0:\"\";s:30:\"column_padding_responsive_unit\";s:2:\"px\";s:20:\"column_padding_right\";s:0:\"\";s:26:\"column_padding_right_large\";s:0:\"\";s:27:\"column_padding_right_medium\";s:0:\"\";s:31:\"column_padding_right_responsive\";s:0:\"\";s:21:\"column_padding_bottom\";s:0:\"\";s:27:\"column_padding_bottom_large\";s:0:\"\";s:28:\"column_padding_bottom_medium\";s:0:\"\";s:32:\"column_padding_bottom_responsive\";s:0:\"\";s:19:\"column_padding_left\";s:0:\"\";s:25:\"column_padding_left_large\";s:0:\"\";s:26:\"column_padding_left_medium\";s:0:\"\";s:30:\"column_padding_left_responsive\";s:0:\"\";s:18:\"module_margins_top\";s:2:\"20\";s:19:\"module_margins_unit\";s:2:\"px\";s:24:\"module_margins_top_large\";s:0:\"\";s:25:\"module_margins_large_unit\";s:2:\"px\";s:25:\"module_margins_top_medium\";s:0:\"\";s:26:\"module_margins_medium_unit\";s:2:\"px\";s:29:\"module_margins_top_responsive\";s:0:\"\";s:30:\"module_margins_responsive_unit\";s:2:\"px\";s:20:\"module_margins_right\";s:2:\"20\";s:26:\"module_margins_right_large\";s:0:\"\";s:27:\"module_margins_right_medium\";s:0:\"\";s:31:\"module_margins_right_responsive\";s:0:\"\";s:21:\"module_margins_bottom\";s:2:\"20\";s:27:\"module_margins_bottom_large\";s:0:\"\";s:28:\"module_margins_bottom_medium\";s:0:\"\";s:32:\"module_margins_bottom_responsive\";s:0:\"\";s:19:\"module_margins_left\";s:2:\"20\";s:25:\"module_margins_left_large\";s:0:\"\";s:26:\"module_margins_left_medium\";s:0:\"\";s:30:\"module_margins_left_responsive\";s:0:\"\";s:12:\"color_scheme\";s:5:\"light\";}s:6:\"layout\";O:8:\"stdClass\":2:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";}}}"],"_fl_builder_draft":["a:0:{}"],"_fl_builder_draft_settings":["O:8:\"stdClass\":2:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";}"],"_product_attributes":["a:13:{s:12:\"pa_thickness\";a:6:{s:4:\"name\";s:12:\"pa_thickness\";s:5:\"value\";s:0:\"\";s:8:\"position\";i:0;s:10:\"is_visible\";i:1;s:12:\"is_variation\";i:0;s:11:\"is_taxonomy\";i:1;}s:7:\"pa_curl\";a:6:{s:4:\"name\";s:7:\"pa_curl\";s:5:\"value\";s:0:\"\";s:8:\"position\";i:1;s:10:\"is_visible\";i:1;s:12:\"is_variation\";i:0;s:11:\"is_taxonomy\";i:1;}s:8:\"pa_color\";a:6:{s:4:\"name\";s:8:\"pa_color\";s:5:\"value\";s:0:\"\";s:8:\"position\";i:2;s:10:\"is_visible\";i:1;s:12:\"is_variation\";i:0;s:11:\"is_taxonomy\";i:1;}s:9:\"pa_length\";a:6:{s:4:\"name\";s:9:\"pa_length\";s:5:\"value\";s:0:\"\";s:8:\"position\";i:3;s:10:\"is_visible\";i:1;s:12:\"is_variation\";i:0;s:11:\"is_taxonomy\";i:1;}s:7:\"pa_line\";a:6:{s:4:\"name\";s:7:\"pa_line\";s:5:\"value\";s:0:\"\";s:8:\"position\";i:4;s:10:\"is_visible\";i:1;s:12:\"is_variation\";i:0;s:11:\"is_taxonomy\";i:1;}s:6:\"pa_moq\";a:6:{s:4:\"name\";s:6:\"pa_moq\";s:5:\"value\";s:0:\"\";s:8:\"position\";i:5;s:10:\"is_visible\";i:1;s:12:\"is_variation\";i:0;s:11:\"is_taxonomy\";i:1;}s:11:\"pa_material\";a:6:{s:4:\"name\";s:11:\"pa_material\";s:5:\"value\";s:0:\"\";s:8:\"position\";i:6;s:10:\"is_visible\";i:1;s:12:\"is_variation\";i:0;s:11:\"is_taxonomy\";i:1;}s:8:\"pa_craft\";a:6:{s:4:\"name\";s:8:\"pa_craft\";s:5:\"value\";s:0:\"\";s:8:\"position\";i:7;s:10:\"is_visible\";i:1;s:12:\"is_variation\";i:0;s:11:\"is_taxonomy\";i:1;}s:16:\"pa_custom-styles\";a:6:{s:4:\"name\";s:16:\"pa_custom-styles\";s:5:\"value\";s:0:\"\";s:8:\"position\";i:8;s:10:\"is_visible\";i:1;s:12:\"is_variation\";i:0;s:11:\"is_taxonomy\";i:1;}s:10:\"pa_odm-oem\";a:6:{s:4:\"name\";s:10:\"pa_odm-oem\";s:5:\"value\";s:0:\"\";s:8:\"position\";i:9;s:10:\"is_visible\";i:1;s:12:\"is_variation\";i:0;s:11:\"is_taxonomy\";i:1;}s:16:\"pa_delivery-time\";a:6:{s:4:\"name\";s:16:\"pa_delivery-time\";s:5:\"value\";s:0:\"\";s:8:\"position\";i:10;s:10:\"is_visible\";i:1;s:12:\"is_variation\";i:0;s:11:\"is_taxonomy\";i:1;}s:15:\"pa_payment-term\";a:6:{s:4:\"name\";s:15:\"pa_payment-term\";s:5:\"value\";s:0:\"\";s:8:\"position\";i:11;s:10:\"is_visible\";i:1;s:12:\"is_variation\";i:0;s:11:\"is_taxonomy\";i:1;}s:16:\"pa_shipment-term\";a:6:{s:4:\"name\";s:16:\"pa_shipment-term\";s:5:\"value\";s:0:\"\";s:8:\"position\";i:12;s:10:\"is_visible\";i:1;s:12:\"is_variation\";i:0;s:11:\"is_taxonomy\";i:1;}}"],"_product_image_gallery":["624,620,619,621,622"],"_wp_old_slug":["0-03mm-classic-lashes"],"rank_math_seo_score":["53"],"rank_math_focus_keyword":["classic lashes mixed tray"],"rank_math_title":["Lashfine-OEM service classic lashes mixed tray factory"],"rank_math_description":["Elevate your lash game with Lashfine \u2013 your premier destination for OEM service classic lashes mixed trays. Unleash creativity with customizable packaging, a spectrum of colors, and the inclusion of your logo. Experience excellence in every lash, exclusively at Lashfine."],"rank_math_primary_product_cat":["0"],"rank_math_analytic_object_id":["75"],"_uag_css_file_name":["uag-css-426.css"],"rank_math_internal_links_processed":["1"],"_uag_page_assets":["a:9:{s:3:\"css\";s:33994:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.uagb-block-e6f939b3.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-e6f939b3.wp-block-uagb-image{text-align: center;justify-content: center;align-self: center;}.uagb-block-e6f939b3 .wp-block-uagb-image__figure{align-items: center;}}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.wp-block-uagb-advanced-heading.uagb-block-64c3d165.wp-block-uagb-advanced-heading {margin-bottom: -20px;}.wp-block-uagb-advanced-heading.uagb-block-64c3d165.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-64c3d165.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-64c3d165.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-64c3d165.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ef07010e.wp-block-uagb-advanced-heading {margin-bottom: -20px;}.wp-block-uagb-advanced-heading.uagb-block-ef07010e.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-ef07010e.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ef07010e.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ef07010e.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-63d4c36f.wp-block-uagb-advanced-heading {margin-bottom: -20px;}.wp-block-uagb-advanced-heading.uagb-block-63d4c36f.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-63d4c36f.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-63d4c36f.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-63d4c36f.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1412ebc7.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-1412ebc7.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1412ebc7.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1412ebc7.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-container.uagb-block-7fa8a7ed .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7fa8a7ed .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7fa8a7ed .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7fa8a7ed .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7fa8a7ed .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7fa8a7ed{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7fa8a7ed > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-7fa8a7ed{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-521f62dc .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-521f62dc .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-521f62dc .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-521f62dc .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-521f62dc .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-521f62dc{max-width: 48%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-521f62dc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-521f62dc{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-7fd3b87e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7fd3b87e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7fd3b87e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7fd3b87e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7fd3b87e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7fd3b87e{max-width: 48%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7fd3b87e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-7fd3b87e{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-1af91c3b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1af91c3b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1af91c3b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1af91c3b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1af91c3b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1af91c3b{max-width: 48%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1af91c3b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-1af91c3b{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-56f970d5 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-56f970d5 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-56f970d5 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-56f970d5 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-56f970d5 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-56f970d5{max-width: 48%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-56f970d5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-56f970d5{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-7fa8a7ed{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7fa8a7ed > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-7fa8a7ed{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-521f62dc{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-521f62dc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-521f62dc{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7fd3b87e{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7fd3b87e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-7fd3b87e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1af91c3b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1af91c3b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-1af91c3b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-56f970d5{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-56f970d5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-56f970d5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-7fa8a7ed{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7fa8a7ed > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-7fa8a7ed{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-521f62dc{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-521f62dc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-521f62dc{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7fd3b87e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7fd3b87e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-7fd3b87e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1af91c3b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1af91c3b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-1af91c3b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-56f970d5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-56f970d5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-56f970d5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}}.wp-block-uagb-container.uagb-block-8abc06a5 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8abc06a5 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8abc06a5 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8abc06a5 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8abc06a5 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8abc06a5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8abc06a5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-8abc06a5{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-9ef0ffec.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-9ef0ffec.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9ef0ffec.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9ef0ffec.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-8abc06a5{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8abc06a5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-8abc06a5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-8abc06a5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8abc06a5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-8abc06a5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}.wp-block-uagb-container.uagb-block-f03be494 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f03be494 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f03be494 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f03be494 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f03be494 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f03be494{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f03be494 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-f03be494{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-f03be494{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f03be494 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-f03be494{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-f03be494{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f03be494 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-f03be494{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:17:{i:0;s:11:\"core\/search\";i:1;s:10:\"core\/group\";i:2;s:12:\"core\/heading\";i:3;s:17:\"core\/latest-posts\";i:4;s:20:\"core\/latest-comments\";i:5;s:13:\"core\/archives\";i:6;s:15:\"core\/categories\";i:7;s:10:\"core\/image\";i:8;s:17:\"core\/social-links\";i:10;s:16:\"core\/social-link\";i:11;s:14:\"core\/paragraph\";i:12;s:10:\"core\/table\";i:13;s:10:\"uagb\/image\";i:14;s:21:\"uagb\/advanced-heading\";i:15;s:30:\"woocommerce\/product-categories\";i:16;s:12:\"core\/gallery\";i:17;s:14:\"uagb\/container\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1788225171\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2023\/02\/0.03mm.jpg",1200,1200,false],"thumbnail":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2023\/02\/0.03mm-150x150.jpg",150,150,true],"medium":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2023\/02\/0.03mm-300x300.jpg",300,300,true],"medium_large":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2023\/02\/0.03mm-768x768.jpg",768,768,true],"large":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2023\/02\/0.03mm-1024x1024.jpg",1024,1024,true],"1536x1536":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2023\/02\/0.03mm.jpg",1200,1200,false],"2048x2048":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2023\/02\/0.03mm.jpg",1200,1200,false],"trp-custom-language-flag":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2023\/02\/0.03mm.jpg",12,12,false],"woocommerce_thumbnail":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2023\/02\/0.03mm-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2023\/02\/0.03mm-600x600.jpg",600,600,true],"woocommerce_gallery_thumbnail":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2023\/02\/0.03mm-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"Miya Chen","author_link":"https:\/\/qdlashfine.com\/nl\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Item Name\uff1aClassic eyelash extensions Thickness\uff1a0.03mm Features\uff1a Natural color: Lashfine black classic lashes bring you a unique and charming natural effect. Big curl: Special curvature technology makes the curls last, giving you a natural and charming appearance or display. Premium materials: The lashes are made of high-quality PBT material and are 100% handmade, soft and natural,&hellip;","_links":{"self":[{"href":"https:\/\/qdlashfine.com\/nl\/wp-json\/wp\/v2\/product\/426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qdlashfine.com\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/qdlashfine.com\/nl\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/qdlashfine.com\/nl\/wp-json\/wp\/v2\/media\/428"}],"wp:attachment":[{"href":"https:\/\/qdlashfine.com\/nl\/wp-json\/wp\/v2\/media?parent=426"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/qdlashfine.com\/nl\/wp-json\/wp\/v2\/product_brand?post=426"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/qdlashfine.com\/nl\/wp-json\/wp\/v2\/product_cat?post=426"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/qdlashfine.com\/nl\/wp-json\/wp\/v2\/product_tag?post=426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}