{"id":4007,"date":"2025-12-25T19:03:29","date_gmt":"2025-12-25T11:03:29","guid":{"rendered":"https:\/\/qdlashfine.com\/?p=4007"},"modified":"2025-12-25T19:03:29","modified_gmt":"2025-12-25T11:03:29","slug":"cuanto-dar-de-propina-por-las-pestanas-de-baddie","status":"publish","type":"post","link":"https:\/\/qdlashfine.com\/es\/cuanto-dar-de-propina-por-las-pestanas-de-baddie\/","title":{"rendered":"Cu\u00e1nto dar de propina por unas pesta\u00f1as de mala muerte: Gu\u00eda completa"},"content":{"rendered":"<h2>Entender la cultura de las propinas en el sector de las pesta\u00f1as<\/h2>\n<p>Cuando se trata de conseguir <em>pesta\u00f1as baddie<\/em>, dar propina a tu t\u00e9cnico de pesta\u00f1as es un gesto que llega muy lejos. Pero, \u00bfcu\u00e1nta propina hay que dar y por qu\u00e9 es importante? Veamos los detalles.<\/p>\n<h3>Por qu\u00e9 es importante dar propina por las pesta\u00f1as de Baddie<\/h3>\n<p>Dar propina no es s\u00f3lo una formalidad; es una forma de mostrar agradecimiento por la habilidad y el esfuerzo que tu artista de las pesta\u00f1as pone en hacerte lucir fabulosa. En el sector de la belleza, especialmente cuando se trata de algo tan complejo como las extensiones de pesta\u00f1as, cada detalle cuenta. Tu t\u00e9cnico de pesta\u00f1as pasa horas aplicando cuidadosamente cada extensi\u00f3n, asegur\u00e1ndose de que est\u00e9n perfectamente alineadas y realzando tu belleza natural. Este nivel de precisi\u00f3n y dedicaci\u00f3n merece un reconocimiento.<\/p>\n<h3>Apoyar la renta y fomentar la excelencia<\/h3>\n<p>Para muchos t\u00e9cnicos de pesta\u00f1as, las propinas son una parte importante de sus ingresos. Tanto si trabajan a comisi\u00f3n como si alquilan un espacio en un sal\u00f3n, sus ingresos pueden ser muy variables. Las propinas no s\u00f3lo les proporcionan estabilidad financiera, sino que tambi\u00e9n les motivan para seguir prestando un servicio excepcional. Todos salimos ganando: t\u00fa consigues unas pesta\u00f1as preciosas y ellos se sienten valorados y apoyados.<\/p>\n<h2>\u00bfCu\u00e1nto dar de propina por las pesta\u00f1as de Baddie?<\/h2>\n<p>\u00bfExiste una cantidad est\u00e1ndar? \u00bfHay que dar siempre propina? \u00bfCu\u00e1nto es demasiado o demasiado poco? Aqu\u00ed tienes un desglose:<\/p>\n<h3>Consejo medio para pesta\u00f1as Baddie<\/h3>\n<p>La propina est\u00e1ndar para los servicios de extensi\u00f3n de pesta\u00f1as suele oscilar entre 15% y 20% del coste del servicio. Este rango refleja una compensaci\u00f3n justa por el tiempo, el esfuerzo y la habilidad que implica su cita para las pesta\u00f1as.<\/p>\n<ul>\n<li><strong>15% Punta:<\/strong> Una cantidad considerada si est\u00e1s satisfecho con el servicio pero tienes un presupuesto ajustado.<\/li>\n<li><strong>Consejo 20%:<\/strong> Refleja un servicio excelente y el aprecio por el duro trabajo de tu artista de pesta\u00f1as.<\/li>\n<\/ul>\n<p>Para ayudarte a calcular las propinas m\u00e1s f\u00e1cilmente, aqu\u00ed tienes un r\u00e1pido desglose basado en los distintos costes de los servicios:<\/p>\n<table>\n<tbody>\n<tr>\n<th>Coste del servicio<\/th>\n<th>15% Punta<\/th>\n<th>20% Consejo<\/th>\n<\/tr>\n<tr>\n<td>$100<\/td>\n<td>$15<\/td>\n<td>$20<\/td>\n<\/tr>\n<tr>\n<td>$150<\/td>\n<td>$22.50<\/td>\n<td>$30<\/td>\n<\/tr>\n<tr>\n<td>$200<\/td>\n<td>$30<\/td>\n<td>$40<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Factores que influyen en la propina de las pesta\u00f1as Baddie<\/h2>\n<p>Determinar la propina adecuada para tu t\u00e9cnico de pesta\u00f1as depende de varios factores, como la calidad del servicio, el tiempo invertido y tu experiencia en general. Si tus pesta\u00f1as tienen un aspecto impresionante, se mantienen perfectamente y realzan tu belleza natural, merece la pena dejar una propina generosa. Adem\u00e1s, si tu t\u00e9cnico se tom\u00f3 el tiempo necesario para asegurarse de que todo se hac\u00eda con cuidado y precisi\u00f3n, en lugar de hacerlo con prisas, esa atenci\u00f3n extra merece un reconocimiento.<\/p>\n<p>Si tu artista de las pesta\u00f1as ha hecho un esfuerzo adicional, como discutir tus preferencias, personalizar el servicio u ofrecerte consejos para el cuidado posterior, ese nivel de dedicaci\u00f3n merece una propina. A la hora de decidir la propina, ten en cuenta tambi\u00e9n la complejidad del servicio. \u00bfFue un retoque r\u00e1pido o un tratamiento completo? \u00bfRealizaron servicios adicionales, como retirar extensiones antiguas o realizar una prueba de alergia? Reflexionar sobre el nivel de personalizaci\u00f3n y el esfuerzo realizado puede ayudarte a determinar una propina adecuada.<\/p>\n<h3>Escenarios de propinas: Cu\u00e1nto dar de propina por unas pesta\u00f1as de malote<\/h3>\n<p><strong>Nombramientos por primera vez:<\/strong> Si visitas a un artista de pesta\u00f1as nuevo, dar una propina generosa (m\u00e1s o menos 20%) puede dejar una impresi\u00f3n positiva y establecer una buena relaci\u00f3n.<\/p>\n<p><strong>Retoques y rellenos:<\/strong> Para los rellenos de pesta\u00f1as, se aplica la misma norma de propina. Si el servicio cuesta menos que un juego completo, ajuste la propina proporcionalmente.<\/p>\n<p><strong>Promociones y descuentos:<\/strong> Si aprovechas un servicio con descuento, basa tu propina en el precio original, no en la tarifa rebajada. As\u00ed te asegurar\u00e1s de que el artista de las pesta\u00f1as se sienta adecuadamente compensado.<\/p>\n<h3>\u00bfHay que dar propina por unas pesta\u00f1as de mala calidad?<\/h3>\n<p>Aunque no es obligatorio dar propina por las extensiones de pesta\u00f1as, siempre es un gesto bienvenido. Es una elecci\u00f3n personal que le permite expresar su gratitud por el servicio y la atenci\u00f3n prestados por su t\u00e9cnico de pesta\u00f1as. Los h\u00e1bitos de propina pueden variar mucho seg\u00fan la persona, las circunstancias o incluso la regi\u00f3n. Algunas personas dejan propina sistem\u00e1ticamente, mientras que otras prefieren no hacerlo. En \u00faltima instancia, la decisi\u00f3n de dejar o no propina -y cu\u00e1nto dejar de propina por las pesta\u00f1as postizas- depende totalmente de usted y de su experiencia.<\/p>\n<h2>C\u00f3mo dar propina a tu artista de las pesta\u00f1as<\/h2>\n<h3>M\u00e9todos de propina<\/h3>\n<ul>\n<li><strong>Consejos sobre efectivo:<\/strong> Siempre apreciado y f\u00e1cil de recibir directamente por su artista.<\/li>\n<li><strong>Consejos sobre tarjetas:<\/strong> Muchos salones permiten a\u00f1adir una propina al pagar con tarjeta. No obstante, confirma con tu artista de pesta\u00f1as si se descuentan comisiones de las propinas con tarjeta.<\/li>\n<li><strong>Venmo o PayPal:<\/strong> Conveniente para quienes no llevan dinero en efectivo, aunque aseg\u00farese de que es aceptable para su t\u00e9cnico.<\/li>\n<\/ul>\n<h3>Cu\u00e1ndo dar propina<\/h3>\n<p>El momento m\u00e1s habitual para dejar propina es justo despu\u00e9s de la cita con el artista, ya sea para un set completo, un relleno o un retoque. Al dejar propina inmediatamente despu\u00e9s del servicio, est\u00e1 mostrando directamente su agradecimiento por los resultados y el esfuerzo del artista. Las extensiones de pesta\u00f1as son un proceso meticuloso y largo que requiere un alto nivel de habilidad, por lo que siempre es una buena idea reconocer esa dedicaci\u00f3n.<\/p>\n<h3>\u00bfDeben los clientes dejar propina si no est\u00e1n satisfechos con el servicio?<\/h3>\n<p>La decisi\u00f3n de dejar o no propina cuando no se est\u00e1 satisfecho con un servicio depende en \u00faltima instancia de cada cliente. Algunos pueden optar por dejar propina como gesto de cortes\u00eda o buena educaci\u00f3n, aunque la experiencia no haya satisfecho sus expectativas. Otros pueden optar por dar una propina reducida u omitirla por completo si no est\u00e1n satisfechos con los resultados.<\/p>\n<p>Si un cliente no est\u00e1 satisfecho, lo mejor es comunicarlo directamente al t\u00e9cnico de pesta\u00f1as o al gerente del sal\u00f3n. A menudo, har\u00e1n un esfuerzo por abordar el problema y resolverlo. Si el proveedor del servicio toma medidas para corregir el problema, dejar una propina completa se considera justo y apreciado.<\/p>\n<p>Es importante reconocer que no todos los problemas de servicio son culpa exclusiva del t\u00e9cnico. La falta de comunicaci\u00f3n, los malentendidos o los problemas t\u00e9cnicos pueden contribuir al resultado. Penalizar al proveedor por algo que escapa a su control puede no ser justo. Sea cual sea la situaci\u00f3n, mantener un tono tranquilo y respetuoso al expresar las preocupaciones permite al t\u00e9cnico o al gestor encontrar una soluci\u00f3n y garantiza una experiencia m\u00e1s positiva en general.<\/p>\n<h2>C\u00f3mo animar a los clientes a que te den propina como artista de las pesta\u00f1as<\/h2>\n<ul>\n<li><strong>Preste un servicio excepcional:<\/strong> C\u00e9ntrese en ofrecer un servicio de primera categor\u00eda asegur\u00e1ndose de que sus clientas est\u00e1n encantadas con sus extensiones de pesta\u00f1as. Esfu\u00e9rzate por alcanzar la perfecci\u00f3n y la profesionalidad en cada cita.<\/li>\n<li><strong>Comunicar con eficacia:<\/strong> Haga saber a los clientes que las propinas siempre son apreciadas e inf\u00f3rmeles amablemente de las distintas formas en que pueden dejarlas.<\/li>\n<li><strong>Haga que las propinas sean c\u00f3modas:<\/strong> Simplifique el proceso de entrega de propinas ofreciendo m\u00faltiples opciones, como dinero en efectivo, plataformas de pago digitales como Venmo u otros m\u00e9todos que prefieran sus clientes.<\/li>\n<li><strong>Cree un entorno relajante:<\/strong> Aseg\u00farese de que su espacio de trabajo sea tranquilo y acogedor para que los clientes puedan relajarse y disfrutar de su cita. Una experiencia positiva suele dar lugar a generosas propinas.<\/li>\n<li><strong>Expresar gratitud:<\/strong> Agradezca siempre a sus clientes que hayan elegido sus servicios y reconozca cualquier consejo que le den con aut\u00e9ntico aprecio.<\/li>\n<li><strong>Mantener la profesionalidad:<\/strong> Sea fiable, puntual y cort\u00e9s. Un comportamiento profesional genera confianza y fomenta la lealtad, animando a los clientes a dejar propina.<\/li>\n<li><strong>Promociona tu trabajo:<\/strong> Utiliza plataformas de redes sociales como Instagram, Facebook y Yelp para mostrar tus habilidades y promocionar tus servicios. Una presencia s\u00f3lida en Internet puede atraer a nuevos clientes que es m\u00e1s probable que dejen propina.<\/li>\n<li><strong>Ofrezca recompensas por recomendaci\u00f3n:<\/strong> Fomente las recomendaciones ofreciendo incentivos o descuentos a los clientes que traigan amigos y familiares a su empresa.<\/li>\n<li><strong>Construir una reputaci\u00f3n estelar:<\/strong> Desarrolle una s\u00f3lida reputaci\u00f3n en su comunidad a trav\u00e9s de un servicio excelente y recomendaciones boca a boca. Los clientes satisfechos que se sienten valorados son m\u00e1s propensos a dejar propinas generosas.<\/li>\n<\/ul>\n<h2>Preguntas frecuentes sobre las propinas de Baddie Eyelashes<\/h2>\n<h3>\u00bfDebo dejar propina si no me ha gustado el servicio?<\/h3>\n<p>Si tu experiencia no ha estado a la altura, no pasa nada por dejar menos propina de lo habitual, pero deja algo. Los comentarios constructivos, acompa\u00f1ados de una propina m\u00e1s peque\u00f1a, demuestran profesionalidad y respeto.<\/p>\n<h3>\u00bfY si mi artista de las pesta\u00f1as es el propietario del negocio?<\/h3>\n<p>La etiqueta para dar propina a los empresarios var\u00eda. Aunque algunos dejan menos propina o ninguna, muchos optan por dar una propina generosa como muestra de agradecimiento por su tiempo y experiencia.<\/p>\n<h3>\u00bfPuedo saltarme la propina?<\/h3>\n<p>Las propinas no son obligatorias, pero s\u00ed muy recomendables. Si no puede dejar propina por motivos econ\u00f3micos, considere la posibilidad de expresar su gratitud mediante un sincero agradecimiento o una cr\u00edtica positiva.<\/p>\n<h2>Conclusi\u00f3n<\/h2>\n<p>Decidir cu\u00e1nto dar de propina por unas pesta\u00f1as de mala muerte es muy f\u00e1cil si has le\u00eddo esta gu\u00eda. Tanto si te ci\u00f1es a la norma 15%-20% como si vas m\u00e1s all\u00e1, seguro que tu artista de las pesta\u00f1as agradecer\u00e1 el gesto. Si conoces las normas y das una propina bien pensada, contribuir\u00e1s a que el sector de la belleza prospere. As\u00ed que, la pr\u00f3xima vez que salgas a la calle con unas pesta\u00f1as preciosas, acu\u00e9rdate de mostrar un poco de cari\u00f1o a la persona que lo hizo posible.<\/p>","protected":false},"excerpt":{"rendered":"<p>Conozca la etiqueta de las propinas para las pesta\u00f1as de mala muerte. Descubra las tarifas est\u00e1ndar, los factores que afectan a las propinas y c\u00f3mo asegurarse de que su artista de pesta\u00f1as se sienta apreciado.<\/p>","protected":false},"author":2,"featured_media":4008,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[93],"tags":[],"class_list":["post-4007","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-styling-application"],"spectra_custom_meta":{"_edit_lock":["1766660547:2"],"_edit_last":["2"],"wpil_sync_report3":["1"],"rank_math_contentai_score":["a:5:{s:8:\"keywords\";s:5:\"74.51\";s:9:\"wordCount\";s:1:\"0\";s:9:\"linkCount\";s:1:\"0\";s:12:\"headingCount\";s:1:\"0\";s:10:\"mediaCount\";s:1:\"0\";}"],"rank_math_seo_score":["75"],"rank_math_focus_keyword":["Baddie Eyelashes"],"_thumbnail_id":["4008"],"site-sidebar-layout":["default"],"ast-site-content-layout":["default"],"site-content-style":["default"],"site-sidebar-style":["default"],"theme-transparent-header-meta":["default"],"astra-migrate-meta-layouts":["set"],"_uag_css_file_name":["uag-css-4007.css"],"rank_math_internal_links_processed":["1"],"_uag_page_assets":["a:9:{s:3:\"css\";s:33994:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.uagb-block-e6f939b3.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-e6f939b3.wp-block-uagb-image{text-align: center;justify-content: center;align-self: center;}.uagb-block-e6f939b3 .wp-block-uagb-image__figure{align-items: center;}}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.wp-block-uagb-advanced-heading.uagb-block-64c3d165.wp-block-uagb-advanced-heading {margin-bottom: -20px;}.wp-block-uagb-advanced-heading.uagb-block-64c3d165.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-64c3d165.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-64c3d165.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-64c3d165.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ef07010e.wp-block-uagb-advanced-heading {margin-bottom: -20px;}.wp-block-uagb-advanced-heading.uagb-block-ef07010e.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-ef07010e.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ef07010e.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ef07010e.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-63d4c36f.wp-block-uagb-advanced-heading {margin-bottom: -20px;}.wp-block-uagb-advanced-heading.uagb-block-63d4c36f.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-63d4c36f.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-63d4c36f.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-63d4c36f.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1412ebc7.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-1412ebc7.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1412ebc7.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1412ebc7.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-container.uagb-block-7fa8a7ed .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7fa8a7ed .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7fa8a7ed .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7fa8a7ed .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7fa8a7ed .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7fa8a7ed{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7fa8a7ed > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-7fa8a7ed{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-521f62dc .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-521f62dc .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-521f62dc .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-521f62dc .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-521f62dc .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-521f62dc{max-width: 48%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-521f62dc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-521f62dc{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-7fd3b87e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7fd3b87e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7fd3b87e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7fd3b87e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7fd3b87e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7fd3b87e{max-width: 48%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7fd3b87e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-7fd3b87e{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-1af91c3b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1af91c3b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1af91c3b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1af91c3b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1af91c3b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1af91c3b{max-width: 48%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1af91c3b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-1af91c3b{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-56f970d5 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-56f970d5 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-56f970d5 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-56f970d5 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-56f970d5 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-56f970d5{max-width: 48%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-56f970d5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-56f970d5{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-7fa8a7ed{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7fa8a7ed > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-7fa8a7ed{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-521f62dc{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-521f62dc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-521f62dc{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7fd3b87e{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7fd3b87e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-7fd3b87e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1af91c3b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1af91c3b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-1af91c3b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-56f970d5{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-56f970d5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-56f970d5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-7fa8a7ed{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7fa8a7ed > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-7fa8a7ed{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-521f62dc{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-521f62dc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-521f62dc{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7fd3b87e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7fd3b87e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-7fd3b87e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1af91c3b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1af91c3b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-1af91c3b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-56f970d5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-56f970d5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-56f970d5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}}.wp-block-uagb-container.uagb-block-8abc06a5 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8abc06a5 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8abc06a5 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8abc06a5 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8abc06a5 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8abc06a5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8abc06a5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-8abc06a5{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-9ef0ffec.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-9ef0ffec.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9ef0ffec.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9ef0ffec.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-8abc06a5{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8abc06a5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-8abc06a5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-8abc06a5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8abc06a5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-8abc06a5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}.wp-block-uagb-container.uagb-block-f03be494 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f03be494 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f03be494 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f03be494 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f03be494 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f03be494{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f03be494 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-f03be494{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-f03be494{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f03be494 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-f03be494{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-f03be494{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f03be494 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-f03be494{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:17:{i:0;s:11:\"core\/search\";i:1;s:10:\"core\/group\";i:2;s:12:\"core\/heading\";i:3;s:17:\"core\/latest-posts\";i:4;s:20:\"core\/latest-comments\";i:5;s:13:\"core\/archives\";i:6;s:15:\"core\/categories\";i:7;s:10:\"core\/image\";i:8;s:17:\"core\/social-links\";i:10;s:16:\"core\/social-link\";i:11;s:14:\"core\/paragraph\";i:12;s:10:\"core\/table\";i:13;s:10:\"uagb\/image\";i:14;s:21:\"uagb\/advanced-heading\";i:15;s:30:\"woocommerce\/product-categories\";i:16;s:12:\"core\/gallery\";i:17;s:14:\"uagb\/container\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1778682370\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/12\/H39addf1abe55418ebde6649bd314fc05y.jpg",1000,1000,false],"thumbnail":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/12\/H39addf1abe55418ebde6649bd314fc05y-150x150.jpg",150,150,true],"medium":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/12\/H39addf1abe55418ebde6649bd314fc05y-300x300.jpg",300,300,true],"medium_large":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/12\/H39addf1abe55418ebde6649bd314fc05y-768x768.jpg",768,768,true],"large":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/12\/H39addf1abe55418ebde6649bd314fc05y.jpg",1000,1000,false],"1536x1536":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/12\/H39addf1abe55418ebde6649bd314fc05y.jpg",1000,1000,false],"2048x2048":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/12\/H39addf1abe55418ebde6649bd314fc05y.jpg",1000,1000,false],"trp-custom-language-flag":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/12\/H39addf1abe55418ebde6649bd314fc05y-12x12.jpg",12,12,true],"woocommerce_thumbnail":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/12\/H39addf1abe55418ebde6649bd314fc05y-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/12\/H39addf1abe55418ebde6649bd314fc05y-600x600.jpg",600,600,true],"woocommerce_gallery_thumbnail":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/12\/H39addf1abe55418ebde6649bd314fc05y-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"xiaoxi99201","author_link":"https:\/\/qdlashfine.com\/es\/author\/xiaoxi99201\/"},"uagb_comment_info":0,"uagb_excerpt":"Learn the etiquette of tipping for baddie eyelashes. Discover the standard rates, factors affecting tips, and how to ensure your lash artist feels appreciated.","_links":{"self":[{"href":"https:\/\/qdlashfine.com\/es\/wp-json\/wp\/v2\/posts\/4007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qdlashfine.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/qdlashfine.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/qdlashfine.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/qdlashfine.com\/es\/wp-json\/wp\/v2\/comments?post=4007"}],"version-history":[{"count":0,"href":"https:\/\/qdlashfine.com\/es\/wp-json\/wp\/v2\/posts\/4007\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/qdlashfine.com\/es\/wp-json\/wp\/v2\/media\/4008"}],"wp:attachment":[{"href":"https:\/\/qdlashfine.com\/es\/wp-json\/wp\/v2\/media?parent=4007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/qdlashfine.com\/es\/wp-json\/wp\/v2\/categories?post=4007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/qdlashfine.com\/es\/wp-json\/wp\/v2\/tags?post=4007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}