{"id":3463,"date":"2025-07-15T18:06:56","date_gmt":"2025-07-15T10:06:56","guid":{"rendered":"https:\/\/qdlashfine.com\/?p=3463"},"modified":"2025-07-15T18:10:30","modified_gmt":"2025-07-15T10:10:30","slug":"guia-de-estilos-de-extensiones-de-pestanas","status":"publish","type":"post","link":"https:\/\/qdlashfine.com\/es\/guia-de-estilos-de-extensiones-de-pestanas\/","title":{"rendered":"Estilos de extensiones de pesta\u00f1as: Gu\u00eda para elegir el conjunto perfecto"},"content":{"rendered":"<p>Las extensiones de pesta\u00f1as se han convertido en uno de los pilares del mundo de la belleza, ya que ofrecen una respuesta sencilla para conseguir unas pesta\u00f1as largas y naturales sin necesidad de aplicar m\u00e1scara a diario. Entre los diferentes estilos y opciones disponibles, el proceso de selecci\u00f3n de la extensi\u00f3n de pesta\u00f1as perfecta puede ser desalentador. Si quieres hacer esa transformaci\u00f3n o simplemente quieres dar un toque sutil a tu look, conocer los tipos de estilos de extensiones de pesta\u00f1as puede ayudarte a decidir cu\u00e1l es el adecuado para ti. Aqu\u00ed descifraremos los estilos m\u00e1s populares <a href=\"https:\/\/qdlashfine.com\/es\/guia-de-estilos-de-extensiones-de-pestanas\/\">estilos de extensi\u00f3n de pesta\u00f1as<\/a> y lo que pueden hacer por sus ojos.<\/p>\n<h2>Pesta\u00f1as cl\u00e1sicas: Elegancia atemporal<\/h2>\n<p>Las extensiones de pesta\u00f1as cl\u00e1sicas son las m\u00e1s tradicionales y las m\u00e1s populares. Este m\u00e9todo adhiere una extensi\u00f3n a una pesta\u00f1a natural. El resultado final es un aspecto natural mejorado que a\u00f1ade volumen y longitud. Las cl\u00e1sicas son perfectas para quienes desean a\u00f1adir algo de longitud y coqueter\u00eda sin complicaciones. Adem\u00e1s, se adaptan perfectamente a quienes tienen las pesta\u00f1as finas o cortas por naturaleza y le ayudar\u00e1n a conseguir un aspecto no demasiado dram\u00e1tico, pero tampoco demasiado sutil.<\/p>\n<p>Lo mejor para: Un estilo natural y sofisticado<\/p>\n<p>Look: Pesta\u00f1as suaves y alargadas<\/p>\n<p>Mantenimiento: De bajo a medio, ya que las pesta\u00f1as naturales se caen y crecen a ritmos variables.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3467 size-full\" src=\"https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Classic-Lashes.jpg\" alt=\"\" width=\"621\" height=\"525\" srcset=\"https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Classic-Lashes.jpg 621w, https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Classic-Lashes-300x254.jpg 300w, https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Classic-Lashes-600x507.jpg 600w\" sizes=\"auto, (max-width: 621px) 100vw, 621px\" \/><\/p>\n<h2>Pesta\u00f1as con volumen: Llenas y esponjosas<\/h2>\n<p>Si a usted le gusta tener un aspecto m\u00e1s voluminoso, las pesta\u00f1as voluminosas son lo que necesita. Este m\u00e9todo a\u00f1ade varias extensiones ligeras a cada pesta\u00f1a natural, lo que da como resultado un aspecto esponjoso y multidimensional. Puedes conseguir unas pesta\u00f1as con volumen que pueden ser de volumen suave o mega volumen, dependiendo del n\u00famero de extensiones que pongan en la pesta\u00f1a. Las pesta\u00f1as escasas se transforman m\u00e1gicamente con este truco: ojos m\u00e1s llenos y sexys.<\/p>\n<p>Perfecto para: Aportar plenitud, dramatismo y volumen a las pesta\u00f1as<\/p>\n<p>Look: Exuberante y voluminoso<\/p>\n<p>Mantenimiento: De moderado a alto, ya que el peso de varias extensiones puede ejercer presi\u00f3n sobre las pesta\u00f1as naturales.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3468\" src=\"https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Volume-Lashes.jpg\" alt=\"\" width=\"634\" height=\"585\" srcset=\"https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Volume-Lashes.jpg 634w, https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Volume-Lashes-300x277.jpg 300w, https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Volume-Lashes-600x554.jpg 600w\" sizes=\"auto, (max-width: 634px) 100vw, 634px\" \/><\/p>\n<h2>Pesta\u00f1as h\u00edbridas: Una maravillosa mezcla de lo cl\u00e1sico y lo voluminoso<\/h2>\n<p>Las pesta\u00f1as h\u00edbridas son ideales para quienes desean una mezcla de ambos mundos. Este look es el estilo cl\u00e1sico combinado con pesta\u00f1as de volumen, que es la combinaci\u00f3n perfecta de longitud y volumen. Las pesta\u00f1as h\u00edbridas presentan una combinaci\u00f3n de extensiones cl\u00e1sicas una a una y abanicos de volumen multipesta\u00f1as, que aportan m\u00e1s dimensi\u00f3n que las pesta\u00f1as cl\u00e1sicas pero no tanto como las pesta\u00f1as de volumen completo. Es ideal para conseguir m\u00e1s elevaci\u00f3n y volumen, pero sin resultar exagerado ni exagerado.<\/p>\n<p>Ideal para: Estilo natural con textura y volumen a\u00f1adidos<\/p>\n<p>Look: Esponjoso sin ser demasiado dram\u00e1tico<\/p>\n<p>Mantenimiento: Regular, ya que este estilo de densidad es m\u00e1s manejable<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3469\" src=\"https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Hybrid-Lashes.jpg\" alt=\"\" width=\"510\" height=\"471\" srcset=\"https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Hybrid-Lashes.jpg 510w, https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Hybrid-Lashes-300x277.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><\/p>\n<h2>Pesta\u00f1as Mega Volumen: Llenas y audaces<\/h2>\n<p>Seamos realistas... Las pesta\u00f1as Mega Volumen son el ep\u00edtome del glamour de las pesta\u00f1as. Este estilo es una combinaci\u00f3n de la t\u00e9cnica de pesta\u00f1as cl\u00e1sicas y de volumen que utiliza extensiones m\u00e1s ligeras con una base plana para poder aplicar m\u00faltiples extensiones en cada pesta\u00f1a natural. Las pesta\u00f1as megavolumen son perfectas para cualquier persona a la que le guste un look espectacular. Este estilo es ideal para ocasiones especiales, sesiones fotogr\u00e1ficas o para cualquier persona a la que le guste un look dram\u00e1tico. Pero recuerda que, como se a\u00f1aden muchas extensiones, este estilo requiere mucho m\u00e1s mantenimiento, ya que m\u00e1s extensiones pueden hacer que tus pesta\u00f1as naturales se caigan m\u00e1s r\u00e1pidamente.<\/p>\n<p>Ideal para: Pesta\u00f1as de infarto<\/p>\n<p>Mira: Extremadamente lleno y oscuro<\/p>\n<p>Mantenimiento: Pesado, tanto como pesan las extensiones<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3473\" src=\"https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Mega-Volume-Lashes.webp\" alt=\"\" width=\"626\" height=\"601\" srcset=\"https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Mega-Volume-Lashes.webp 1170w, https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Mega-Volume-Lashes-300x288.webp 300w, https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Mega-Volume-Lashes-1024x982.webp 1024w, https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Mega-Volume-Lashes-768x736.webp 768w, https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Mega-Volume-Lashes-600x575.webp 600w\" sizes=\"auto, (max-width: 626px) 100vw, 626px\" \/><\/p>\n<h2>Pesta\u00f1as Cat Eye: Elevaci\u00f3n y extensi\u00f3n<\/h2>\n<p>Las pesta\u00f1as Cat-eye tienen forma de ojos almendrados y levantados. Las extensiones son m\u00e1s largas en el exterior del ojo y se estrechan hacia el interior. Esta forma imita el aspecto de un delineado \u201cojo de gato\u201d que acent\u00faa el arco natural del ojo. Pesta\u00f1as para mirada de gato: Si buscas una mirada angulosa y sensual que se centre en la esquina exterior de los ojos, las pesta\u00f1as de ojo de gato son las mejores para ti.<\/p>\n<p>Ideal para: Ojos levantados, sensuales y alargados<\/p>\n<p>Mira: Dram\u00e1tico y revelador<\/p>\n<p>Mantenimiento: moderado si se aplica en los \u00e1ngulos exteriores de la l\u00ednea de las pesta\u00f1as<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3470\" src=\"https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Cat-Eye-Lashes.jpg\" alt=\"\" width=\"600\" height=\"600\" srcset=\"https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Cat-Eye-Lashes.jpg 600w, https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Cat-Eye-Lashes-300x300.jpg 300w, https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Cat-Eye-Lashes-150x150.jpg 150w, https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Cat-Eye-Lashes-100x100.jpg 100w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<h2>Pesta\u00f1as de mu\u00f1eca: Sutiles y anchas<\/h2>\n<p>Las pesta\u00f1as de mu\u00f1eca se crean para que los ojos parezcan m\u00e1s j\u00f3venes y anchos. Suelen ser m\u00e1s largas en el centro de la l\u00ednea de las pesta\u00f1as y m\u00e1s cortas en las esquinas exteriores e interiores. Esto da un aspecto de ojos abiertos, con una redondez similar a la de los ojos de una mu\u00f1eca. Si buscas una mirada dulce e inocente con un poco m\u00e1s de va-va-voom, las pesta\u00f1as de ojos de mu\u00f1eca son una gran opci\u00f3n.<\/p>\n<p>Lo mejor para: Una mirada de ojos abiertos y dulce que es muy joven de coraz\u00f3n<\/p>\n<p>Aspecto: Suave y redondo en el centro y con volumen.<\/p>\n<p>Mantenimiento: Poco mantenimiento - prestando atenci\u00f3n a la parte media de las pesta\u00f1as.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3471\" src=\"https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Doll-Eye-Lashes.jpg\" alt=\"\" width=\"792\" height=\"445\" srcset=\"https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Doll-Eye-Lashes.jpg 1176w, https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Doll-Eye-Lashes-300x169.jpg 300w, https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Doll-Eye-Lashes-1024x576.jpg 1024w, https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Doll-Eye-Lashes-768x432.jpg 768w, https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Doll-Eye-Lashes-600x337.jpg 600w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/p>\n<h2>\u00a1Pesta\u00f1as Wispy - Unas pesta\u00f1as que abren los ojos Las pesta\u00f1as Wispy son m\u00e1s divertidas y coquetas!<\/h2>\n<p>Las pesta\u00f1as Wispy son populares entre quienes desean un look natural pero texturizado. Este dise\u00f1o utiliza extensiones de longitud variable para conseguir unas pesta\u00f1as suaves y en capas que imitan a la perfecci\u00f3n la textura de las pesta\u00f1as reales. M\u00e1s definici\u00f3n Si prefiere las pesta\u00f1as onduladas, le encantar\u00e1 la longitud y el grosor a\u00f1adidos a lo largo de toda la l\u00ednea de las pesta\u00f1as sin sobrecargarlas. Este look crea unas pesta\u00f1as ligeramente onduladas con un toque de glamour.<\/p>\n<p>Lo mejor para: Un look m\u00e1s natural y menos estilizado<\/p>\n<p>Look: Suave, ondeante y con textura<\/p>\n<p>Mantenimiento: F\u00e1cil a medio, dependiendo del volumen que quieras<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3472\" src=\"https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Wispy-Lashes.jpg\" alt=\"\" width=\"513\" height=\"430\" srcset=\"https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Wispy-Lashes.jpg 449w, https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Wispy-Lashes-300x251.jpg 300w\" sizes=\"auto, (max-width: 513px) 100vw, 513px\" \/><\/p>\n<h2>Pesta\u00f1as rusas: Precisi\u00f3n y dramatismo<\/h2>\n<p>Las pesta\u00f1as rusas son una forma avanzada de pesta\u00f1as de volumen, en la que se utilizan pesta\u00f1as ultraligeras y se aplican de la misma forma que la aplicaci\u00f3n cl\u00e1sica, pero en abanicos de 2 a 7 pesta\u00f1as. Este m\u00e9todo permite conseguir una mirada m\u00e1s redondeada, con m\u00e1s volumen y aireada. Las pesta\u00f1as rusas son adecuadas para las personas que desean un look glamuroso pero no se sienten c\u00f3modas: pueden ser tan naturales u oscuras como desee el cliente. Se trata de una t\u00e9cnica muy sofisticada que requiere retoques peri\u00f3dicos para mantener el estilo.<\/p>\n<p>Para qui\u00e9n es mejor: Un look espec\u00edfico, dram\u00e1tico y ligero<\/p>\n<p>Look:Gruesa, rellena y voluminosa sin peso.<\/p>\n<p>Mantenimiento: Alto (maniobra delicada y complicada)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3474\" src=\"https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Russian-Lashes.jpg\" alt=\"\" width=\"766\" height=\"427\" srcset=\"https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Russian-Lashes.jpg 901w, https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Russian-Lashes-300x167.jpg 300w, https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Russian-Lashes-768x428.jpg 768w, https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Russian-Lashes-600x334.jpg 600w\" sizes=\"auto, (max-width: 766px) 100vw, 766px\" \/><\/p>\n<h2>Pesta\u00f1as Kim K: Lush y Lush<\/h2>\n<p>Las pesta\u00f1as de Kim K son voluminosas y espectaculares, y a veces se las conoce como el look caracter\u00edstico de la estrella. Este look es la combinaci\u00f3n perfecta de volumen y longitud, para una l\u00ednea de pesta\u00f1as abundante y oscura, atrevida pero sofisticada. Las pesta\u00f1as de Kim K son ideales para las que quieren unas pesta\u00f1as voluminosas que griten alfombra roja. Este estilo es ideal tanto para el d\u00eda como para la noche, sobre todo si quieres destacar.<\/p>\n<p>Ideal para: Amplificar tus pesta\u00f1as, a\u00f1adir volumen y dar dramatismo.Dimensiones 0.23 oz\\Persistencia Esta m\u00e1scara favorita de culto puede durar todo el d\u00eda y no se desmorona.<\/p>\n<p>Look: Atrevido, oscuro y voluminoso<\/p>\n<p>Mantenimiento: Alto; las pesta\u00f1as son pesadas y gruesas<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3475\" src=\"https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Kim-K-Lashes.webp\" alt=\"\" width=\"657\" height=\"344\" srcset=\"https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Kim-K-Lashes.webp 1200w, https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Kim-K-Lashes-300x157.webp 300w, https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Kim-K-Lashes-1024x536.webp 1024w, https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Kim-K-Lashes-768x402.webp 768w, https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Kim-K-Lashes-600x314.webp 600w\" sizes=\"auto, (max-width: 657px) 100vw, 657px\" \/><\/p>\n<h2>Conclusi\u00f3n<\/h2>\n<p>El estilo de extensiones de pesta\u00f1as por el que deber\u00eda decantarse depende realmente de su tipo de pesta\u00f1as naturales, del look que quiera conseguir y del tiempo que est\u00e9 dispuesta a dedicar a su rutina matutina). Tanto si quieres realzar tus pesta\u00f1as naturales como si no puedes ir a una fiesta sin una mirada completa y espectacular, hay un estilo para cada persona. Comente con su t\u00e9cnico de pesta\u00f1as qu\u00e9 tipo de extensi\u00f3n de pesta\u00f1as se adapta mejor a su personalidad, a la forma de sus ojos y a su estilo de vida. Sea la envidia de las reinas de la belleza de todo el mundo con un estilo perfecto que proporcione a sus ojos el destello justo, sea cual sea su rutina.<\/p>","protected":false},"excerpt":{"rendered":"<p>Eyelash Extensions have become such a mainstay of the beauty world, providing an easy answer to a long full natural lash with no daily mascara application required. Between the different styles and options available, the process of selecting the perfect eyelash extension can be daunting. If you want to make that transformation or just want [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3474,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[93],"tags":[],"class_list":["post-3463","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-styling-application"],"spectra_custom_meta":{"_edit_lock":["1752574177:2"],"_edit_last":["2"],"rank_math_seo_score":["78"],"rank_math_contentai_score":["a:5:{s:8:\"keywords\";s:5:\"74.51\";s:9:\"wordCount\";s:1:\"0\";s:9:\"linkCount\";s:1:\"0\";s:12:\"headingCount\";s:1:\"0\";s:10:\"mediaCount\";s:1:\"0\";}"],"rank_math_focus_keyword":["Eyelash Extension Styles"],"rank_math_primary_category":["93"],"site-sidebar-layout":["default"],"ast-site-content-layout":["default"],"site-content-style":["default"],"site-sidebar-style":["default"],"theme-transparent-header-meta":["default"],"_thumbnail_id":["3474"],"rank_math_analytic_object_id":["94"],"astra-migrate-meta-layouts":["set"],"_uag_css_file_name":["uag-css-3463.css"],"rank_math_internal_links_processed":["1"],"_uag_page_assets":["a:9:{s:3:\"css\";s:33994:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.uagb-block-e6f939b3.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-e6f939b3.wp-block-uagb-image{text-align: center;justify-content: center;align-self: center;}.uagb-block-e6f939b3 .wp-block-uagb-image__figure{align-items: center;}}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.wp-block-uagb-advanced-heading.uagb-block-64c3d165.wp-block-uagb-advanced-heading {margin-bottom: -20px;}.wp-block-uagb-advanced-heading.uagb-block-64c3d165.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-64c3d165.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-64c3d165.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-64c3d165.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ef07010e.wp-block-uagb-advanced-heading {margin-bottom: -20px;}.wp-block-uagb-advanced-heading.uagb-block-ef07010e.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-ef07010e.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ef07010e.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ef07010e.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-63d4c36f.wp-block-uagb-advanced-heading {margin-bottom: -20px;}.wp-block-uagb-advanced-heading.uagb-block-63d4c36f.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-63d4c36f.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-63d4c36f.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-63d4c36f.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1412ebc7.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-1412ebc7.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1412ebc7.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1412ebc7.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-container.uagb-block-7fa8a7ed .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7fa8a7ed .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7fa8a7ed .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7fa8a7ed .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7fa8a7ed .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7fa8a7ed{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7fa8a7ed > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-7fa8a7ed{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-521f62dc .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-521f62dc .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-521f62dc .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-521f62dc .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-521f62dc .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-521f62dc{max-width: 48%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-521f62dc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-521f62dc{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-7fd3b87e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7fd3b87e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7fd3b87e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7fd3b87e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7fd3b87e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7fd3b87e{max-width: 48%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7fd3b87e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-7fd3b87e{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-1af91c3b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1af91c3b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1af91c3b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1af91c3b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1af91c3b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1af91c3b{max-width: 48%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1af91c3b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-1af91c3b{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-56f970d5 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-56f970d5 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-56f970d5 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-56f970d5 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-56f970d5 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-56f970d5{max-width: 48%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-56f970d5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-56f970d5{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-7fa8a7ed{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7fa8a7ed > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-7fa8a7ed{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-521f62dc{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-521f62dc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-521f62dc{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7fd3b87e{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7fd3b87e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-7fd3b87e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1af91c3b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1af91c3b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-1af91c3b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-56f970d5{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-56f970d5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-56f970d5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-7fa8a7ed{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7fa8a7ed > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-7fa8a7ed{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-521f62dc{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-521f62dc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-521f62dc{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7fd3b87e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7fd3b87e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-7fd3b87e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1af91c3b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1af91c3b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-1af91c3b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-56f970d5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-56f970d5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-56f970d5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}}.wp-block-uagb-container.uagb-block-8abc06a5 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8abc06a5 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8abc06a5 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8abc06a5 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8abc06a5 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8abc06a5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8abc06a5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-8abc06a5{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-9ef0ffec.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-9ef0ffec.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9ef0ffec.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9ef0ffec.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-8abc06a5{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8abc06a5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-8abc06a5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-8abc06a5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8abc06a5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-8abc06a5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}.wp-block-uagb-container.uagb-block-f03be494 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f03be494 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f03be494 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f03be494 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f03be494 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f03be494{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f03be494 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-f03be494{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-f03be494{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f03be494 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-f03be494{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-f03be494{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f03be494 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-f03be494{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:17:{i:0;s:11:\"core\/search\";i:1;s:10:\"core\/group\";i:2;s:12:\"core\/heading\";i:3;s:17:\"core\/latest-posts\";i:4;s:20:\"core\/latest-comments\";i:5;s:13:\"core\/archives\";i:6;s:15:\"core\/categories\";i:7;s:10:\"core\/image\";i:8;s:17:\"core\/social-links\";i:10;s:16:\"core\/social-link\";i:11;s:14:\"core\/paragraph\";i:12;s:10:\"core\/table\";i:13;s:10:\"uagb\/image\";i:14;s:21:\"uagb\/advanced-heading\";i:15;s:30:\"woocommerce\/product-categories\";i:16;s:12:\"core\/gallery\";i:17;s:14:\"uagb\/container\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1778682370\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Russian-Lashes.jpg",901,502,false],"thumbnail":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Russian-Lashes-150x150.jpg",150,150,true],"medium":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Russian-Lashes-300x167.jpg",300,167,true],"medium_large":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Russian-Lashes-768x428.jpg",768,428,true],"large":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Russian-Lashes.jpg",901,502,false],"1536x1536":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Russian-Lashes.jpg",901,502,false],"2048x2048":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Russian-Lashes.jpg",901,502,false],"trp-custom-language-flag":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Russian-Lashes.jpg",18,10,false],"woocommerce_thumbnail":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Russian-Lashes-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Russian-Lashes-600x334.jpg",600,334,true],"woocommerce_gallery_thumbnail":["https:\/\/qdlashfine.com\/wp-content\/uploads\/2025\/07\/Russian-Lashes-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"xiaoxi99201","author_link":"https:\/\/qdlashfine.com\/es\/author\/xiaoxi99201\/"},"uagb_comment_info":0,"uagb_excerpt":"Eyelash Extensions have become such a mainstay of the beauty world, providing an easy answer to a long full natural lash with no daily mascara application required. Between the different styles and options available, the process of selecting the perfect eyelash extension can be daunting. If you want to make that transformation or just want&hellip;","_links":{"self":[{"href":"https:\/\/qdlashfine.com\/es\/wp-json\/wp\/v2\/posts\/3463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qdlashfine.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/qdlashfine.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/qdlashfine.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/qdlashfine.com\/es\/wp-json\/wp\/v2\/comments?post=3463"}],"version-history":[{"count":0,"href":"https:\/\/qdlashfine.com\/es\/wp-json\/wp\/v2\/posts\/3463\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/qdlashfine.com\/es\/wp-json\/wp\/v2\/media\/3474"}],"wp:attachment":[{"href":"https:\/\/qdlashfine.com\/es\/wp-json\/wp\/v2\/media?parent=3463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/qdlashfine.com\/es\/wp-json\/wp\/v2\/categories?post=3463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/qdlashfine.com\/es\/wp-json\/wp\/v2\/tags?post=3463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}